{"id":1990,"date":"2018-03-09T12:32:25","date_gmt":"2018-03-09T11:32:25","guid":{"rendered":"https:\/\/joz.nl\/joz-districtwinnaar-metaalunie-smart-manufacturing-award\/"},"modified":"2024-01-05T08:48:12","modified_gmt":"2024-01-05T07:48:12","slug":"smart-manufacturing-award-der-niederlandischen-metaalunie","status":"publish","type":"post","link":"https:\/\/joz.nl\/de\/smart-manufacturing-award-der-niederlandischen-metaalunie\/","title":{"rendered":"JOZ Bezirkssieger des Smart Manufacturing Awards der niederl\u00e4ndischen Metaalunie"},"content":{"rendered":"\n<div class=\"wp-block-g2p-wrapper\"><div class=\"container\"><div class=\"row\"><div class=\"col-12\">\n<p class=\"has-medium-font-size wp-block-paragraph\">Die Bezirkssieger und die nationalen Gewinner des <a href=\"https:\/\/metaalunie.nl\/Actueel\" target=\"_blank\" rel=\"noreferrer noopener\">Smart Manufacturing Awards der niederl\u00e4ndischen Metaalunie<\/a> stehen fest. Unter der Leitung von Micha\u00ebl van Straalen (dem Vorsitzenden von MKB-Nederland) hat die Jury am 8. Dezember aus allen Einsendungen 9 Bezirkssieger gek\u00fcrt. Beim nationalen Finale am 7. M\u00e4rz 2018 sind auf der Jahresmesse in Utrecht 3 Nominierungen aus allen Siegern ausgew\u00e4hlt und der nationale Gewinner bekannt gegeben worden.<\/p>\n\n\n\n<h2 class=\"wp-block-heading small\"><strong>\u00dcberlegen UND tun<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Micha\u00ebl van Straalen: \u201eAlle Sieger verstehen, dass die Kraft unserer Produktion darin besteht, dass wir uns etwas \u00fcberlegen und es dann auch tun, und zwar gleicherma\u00dfen jetzt wie auch in Zukunft. F\u00fcr einen rentablen Betrieb ist das sehr wichtig. Ich war sehr gespannt, welcher der ausgezeichneten Bezirkssieger den Award bekommen w\u00fcrde.\u201c<\/p>\n\n\n\n<h2 class=\"wp-block-heading small\"><strong>JOZ: Bezirkssieger f\u00fcr den Nordwesten<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">9 Bezirkssieger, 3 Nominierungen, ein Nachmittag und ein Abend voller Inspiration mit tollen Rednern und sch\u00f6nen Beispielen aus einer phantastischen Branche. JOZ wurde aus 1 100 Unternehmen zum Bezirkssieger f\u00fcr den Nordwesten ausgew\u00e4hlt. Das haben wir der Tatsache zu verdanken, dass wir als <a href=\"https:\/\/joz.nl\/de\/uber-joz\/\">innovatives Unternehmen<\/a> mit traditionellen Materialien arbeiten und in Sachen Automatisierung und Roboterisierung auf der H\u00f6he der Zeit sind. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir setzen auf nachhaltige Produkte, die zuverl\u00e4ssig, stabil und modular einsetzbar sind, und passen auch in dieser Hinsicht zur Lean-Philosophie. Au\u00dferdem ist JOZ gem\u00e4\u00df <a href=\"https:\/\/joz.nl\/de\/uber-joz\/qualitat\/\">ISO zertifiziert<\/a>, sprich die Prozesse in unserem Unternehmen sind optimiert.<\/p>\n\n\n\n<h2 class=\"wp-block-heading small\"><strong>Der Smart Manufacturing Award der niederl\u00e4ndischen Metaalunie<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die niederl\u00e4ndische Koninklijke Metaalunie stellt jedes Jahr einen Preis f\u00fcr ein Mitgliedsunternehmen der Metaalunie zur Verf\u00fcgung, das sich bei einem aktuellen Thema besonders hervorhebt. In diesem Jahr lautet das Thema \u201aSmart Manufacturing\u2018 bzw. schlaue Produktion. M\u00f6glich sind beispielsweise der optimale Einsatz von modernen Produktionsverfahren, ausgezeichnete Prozesse, gute Materialentscheidungen, durchdachte Systeme, Digitalisierung und eine selbst steuernde und selbst lernende Organisation.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der nationale Gewinner des Smart Manufacturing Award ist Aebi Schmidt Nederland bv aus Holten. Das war der Bezirkssieger f\u00fcr die Region Ost.<\/p>\n\n\n\n<h2 class=\"wp-block-heading small\">Die jury<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Nebem dem Jury-Pr\u00e4sidenten Micha\u00ebl van Straalen (Vorsitzender MKB-Nederland) bestand die Jury aus Rolf Elling (Chefredakteur von Vraag en Aanbod), Gu van Rhijn (Senior Project Manager &amp; Researcher bei TNO), Mark Helder (Managing Director HGG International bv und Sieger des Preises der Metaalunie im Jahr 2017) sowie David Pappie (Direktor Spitzensektoren und Industrief\u00fchrung bei der Generaldirektion Betriebliches Leben und Innovation im niederl\u00e4ndischen Wirtschaftsministerium).&nbsp;<\/p>\n<\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Die Bezirkssieger und die nationalen Gewinner des Smart Manufacturing Awards der niederl\u00e4ndischen Metaalunie stehen fest. Unter der Leitung von Micha\u00ebl van Straalen (dem Vorsitzenden von MKB-Nederland) hat die Jury am 8. Dezember aus allen Einsendungen 9 Bezirkssieger gek\u00fcrt. Beim nationalen Finale am 7. M\u00e4rz 2018 sind auf der Jahresmesse in Utrecht 3 Nominierungen aus allen Siegern ausgew\u00e4hlt und der nationale Gewinner bekannt gegeben worden.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[77],"tags":[],"class_list":["post-1990","post","type-post","status-publish","format-standard","hentry","category-nieuws-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Smart Manufacturing Awards der niederl\u00e4ndischen Metaalunie | JOZ<\/title>\n<meta name=\"description\" content=\"JOZ ist der Bezirkssieger Nordwest im Smart Manufacturing Award der niederl\u00e4ndischen Metaalunie. Hier erfahren Sie, warum wir diesen Preis bekommen haben.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/joz.nl\/de\/smart-manufacturing-award-der-niederlandischen-metaalunie\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Smart Manufacturing Awards der niederl\u00e4ndischen Metaalunie | JOZ\" \/>\n<meta property=\"og:description\" content=\"JOZ ist der Bezirkssieger Nordwest im Smart Manufacturing Award der niederl\u00e4ndischen Metaalunie. Hier erfahren Sie, warum wir diesen Preis bekommen haben.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/joz.nl\/de\/smart-manufacturing-award-der-niederlandischen-metaalunie\/\" \/>\n<meta property=\"og:site_name\" content=\"JOZ\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-09T11:32:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-05T07:48:12+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/joz.nl\\\/de\\\/smart-manufacturing-award-der-niederlandischen-metaalunie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/joz.nl\\\/de\\\/smart-manufacturing-award-der-niederlandischen-metaalunie\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/joz.nl\\\/de\\\/#\\\/schema\\\/person\\\/6c8e8c387d506c689f369cdd4b0b6d36\"},\"headline\":\"JOZ Bezirkssieger des Smart Manufacturing Awards der niederl\u00e4ndischen Metaalunie\",\"datePublished\":\"2018-03-09T11:32:25+00:00\",\"dateModified\":\"2024-01-05T07:48:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/joz.nl\\\/de\\\/smart-manufacturing-award-der-niederlandischen-metaalunie\\\/\"},\"wordCount\":397,\"commentCount\":0,\"articleSection\":[\"News\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/joz.nl\\\/de\\\/smart-manufacturing-award-der-niederlandischen-metaalunie\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/joz.nl\\\/de\\\/smart-manufacturing-award-der-niederlandischen-metaalunie\\\/\",\"url\":\"https:\\\/\\\/joz.nl\\\/de\\\/smart-manufacturing-award-der-niederlandischen-metaalunie\\\/\",\"name\":\"Smart Manufacturing Awards der niederl\u00e4ndischen Metaalunie | JOZ\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/joz.nl\\\/de\\\/#website\"},\"datePublished\":\"2018-03-09T11:32:25+00:00\",\"dateModified\":\"2024-01-05T07:48:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/joz.nl\\\/de\\\/#\\\/schema\\\/person\\\/6c8e8c387d506c689f369cdd4b0b6d36\"},\"description\":\"JOZ ist der Bezirkssieger Nordwest im Smart Manufacturing Award der niederl\u00e4ndischen Metaalunie. Hier erfahren Sie, warum wir diesen Preis bekommen haben.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/joz.nl\\\/de\\\/smart-manufacturing-award-der-niederlandischen-metaalunie\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/joz.nl\\\/de\\\/smart-manufacturing-award-der-niederlandischen-metaalunie\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/joz.nl\\\/de\\\/smart-manufacturing-award-der-niederlandischen-metaalunie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/joz.nl\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/joz.nl\\\/de\\\/category\\\/nieuws-de\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"JOZ Bezirkssieger des Smart Manufacturing Awards der niederl\u00e4ndischen Metaalunie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/joz.nl\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/joz.nl\\\/de\\\/\",\"name\":\"JOZ\",\"description\":\"Home of the clean stable\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/joz.nl\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/joz.nl\\\/de\\\/#\\\/schema\\\/person\\\/6c8e8c387d506c689f369cdd4b0b6d36\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17871f2f891ac62309f8901eca9bb3ba737cb8bd5673877ed4b075f338e8a402?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17871f2f891ac62309f8901eca9bb3ba737cb8bd5673877ed4b075f338e8a402?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17871f2f891ac62309f8901eca9bb3ba737cb8bd5673877ed4b075f338e8a402?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"description\":\"Maecenas et condimentum libero, id consequat quam. Nam lorem tortor, aliquet vel ipsum eu, scelerisque placerat nulla. Vestibulum fringilla, neque ut venenatis vulputate, purus ligula commodo purus, eget finibus quam enim non erat. Donec hendrerit nulla a augue finibus, eget vehicula est feugiat.\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Smart Manufacturing Awards der niederl\u00e4ndischen Metaalunie | JOZ","description":"JOZ ist der Bezirkssieger Nordwest im Smart Manufacturing Award der niederl\u00e4ndischen Metaalunie. Hier erfahren Sie, warum wir diesen Preis bekommen haben.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/joz.nl\/de\/smart-manufacturing-award-der-niederlandischen-metaalunie\/","og_locale":"de_DE","og_type":"article","og_title":"Smart Manufacturing Awards der niederl\u00e4ndischen Metaalunie | JOZ","og_description":"JOZ ist der Bezirkssieger Nordwest im Smart Manufacturing Award der niederl\u00e4ndischen Metaalunie. Hier erfahren Sie, warum wir diesen Preis bekommen haben.","og_url":"https:\/\/joz.nl\/de\/smart-manufacturing-award-der-niederlandischen-metaalunie\/","og_site_name":"JOZ","article_published_time":"2018-03-09T11:32:25+00:00","article_modified_time":"2024-01-05T07:48:12+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"admin","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/joz.nl\/de\/smart-manufacturing-award-der-niederlandischen-metaalunie\/#article","isPartOf":{"@id":"https:\/\/joz.nl\/de\/smart-manufacturing-award-der-niederlandischen-metaalunie\/"},"author":{"name":"admin","@id":"https:\/\/joz.nl\/de\/#\/schema\/person\/6c8e8c387d506c689f369cdd4b0b6d36"},"headline":"JOZ Bezirkssieger des Smart Manufacturing Awards der niederl\u00e4ndischen Metaalunie","datePublished":"2018-03-09T11:32:25+00:00","dateModified":"2024-01-05T07:48:12+00:00","mainEntityOfPage":{"@id":"https:\/\/joz.nl\/de\/smart-manufacturing-award-der-niederlandischen-metaalunie\/"},"wordCount":397,"commentCount":0,"articleSection":["News"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/joz.nl\/de\/smart-manufacturing-award-der-niederlandischen-metaalunie\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/joz.nl\/de\/smart-manufacturing-award-der-niederlandischen-metaalunie\/","url":"https:\/\/joz.nl\/de\/smart-manufacturing-award-der-niederlandischen-metaalunie\/","name":"Smart Manufacturing Awards der niederl\u00e4ndischen Metaalunie | JOZ","isPartOf":{"@id":"https:\/\/joz.nl\/de\/#website"},"datePublished":"2018-03-09T11:32:25+00:00","dateModified":"2024-01-05T07:48:12+00:00","author":{"@id":"https:\/\/joz.nl\/de\/#\/schema\/person\/6c8e8c387d506c689f369cdd4b0b6d36"},"description":"JOZ ist der Bezirkssieger Nordwest im Smart Manufacturing Award der niederl\u00e4ndischen Metaalunie. Hier erfahren Sie, warum wir diesen Preis bekommen haben.","breadcrumb":{"@id":"https:\/\/joz.nl\/de\/smart-manufacturing-award-der-niederlandischen-metaalunie\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/joz.nl\/de\/smart-manufacturing-award-der-niederlandischen-metaalunie\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/joz.nl\/de\/smart-manufacturing-award-der-niederlandischen-metaalunie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/joz.nl\/de\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/joz.nl\/de\/category\/nieuws-de\/"},{"@type":"ListItem","position":3,"name":"JOZ Bezirkssieger des Smart Manufacturing Awards der niederl\u00e4ndischen Metaalunie"}]},{"@type":"WebSite","@id":"https:\/\/joz.nl\/de\/#website","url":"https:\/\/joz.nl\/de\/","name":"JOZ","description":"Home of the clean stable","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/joz.nl\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/joz.nl\/de\/#\/schema\/person\/6c8e8c387d506c689f369cdd4b0b6d36","name":"admin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/17871f2f891ac62309f8901eca9bb3ba737cb8bd5673877ed4b075f338e8a402?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17871f2f891ac62309f8901eca9bb3ba737cb8bd5673877ed4b075f338e8a402?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17871f2f891ac62309f8901eca9bb3ba737cb8bd5673877ed4b075f338e8a402?s=96&d=mm&r=g","caption":"admin"},"description":"Maecenas et condimentum libero, id consequat quam. Nam lorem tortor, aliquet vel ipsum eu, scelerisque placerat nulla. Vestibulum fringilla, neque ut venenatis vulputate, purus ligula commodo purus, eget finibus quam enim non erat. Donec hendrerit nulla a augue finibus, eget vehicula est feugiat."}]}},"_links":{"self":[{"href":"https:\/\/joz.nl\/de\/wp-json\/wp\/v2\/posts\/1990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/joz.nl\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/joz.nl\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/joz.nl\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/joz.nl\/de\/wp-json\/wp\/v2\/comments?post=1990"}],"version-history":[{"count":4,"href":"https:\/\/joz.nl\/de\/wp-json\/wp\/v2\/posts\/1990\/revisions"}],"predecessor-version":[{"id":20794,"href":"https:\/\/joz.nl\/de\/wp-json\/wp\/v2\/posts\/1990\/revisions\/20794"}],"wp:attachment":[{"href":"https:\/\/joz.nl\/de\/wp-json\/wp\/v2\/media?parent=1990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/joz.nl\/de\/wp-json\/wp\/v2\/categories?post=1990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/joz.nl\/de\/wp-json\/wp\/v2\/tags?post=1990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}