{"id":1823,"date":"2019-08-30T15:01:14","date_gmt":"2019-08-30T13:01:14","guid":{"rendered":"https:\/\/joz.nl\/privacybeleid\/"},"modified":"2020-06-15T11:46:40","modified_gmt":"2020-06-15T09:46:40","slug":"declaration-de-confidentialite","status":"publish","type":"page","link":"https:\/\/joz.nl\/fr\/declaration-de-confidentialite\/","title":{"rendered":"D\u00e9claration de confidentialit\u00e9"},"content":{"rendered":"\n<div class=\"wp-block-g2p-wrapper\"><div class=\"container\"><div class=\"row\"><div class=\"col-12\">\n<h2 class=\"small wp-block-heading\"><strong>Introduction<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Chez JOZ, nous estimons qu\u2019il est tr\u00e8s important de prot\u00e9ger la confidentialit\u00e9 de nos clients et des visiteurs du site web. Nous traitons et prot\u00e9geons donc vos donn\u00e9es professionnelles et personnelles avec le plus grand soin. JOZ b.v. adh\u00e8re aux exigences du R\u00e8glement g\u00e9n\u00e9ral sur la protection des donn\u00e9es.<\/p>\n\n\n\n<h2 class=\"small wp-block-heading\"><strong>Fondement du traitement<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Nous partons du principe que nous ne traitons que des donn\u00e9es ayant un objectif particulier. En ce sens, nous respectons les (ou un des) principes suivants\u00a0:<\/p>\n\n\n\n<ul class=\"children_has_gear_icon\">\n<li>Consentement de la personne concern\u00e9e<\/li>\n<li>Obligation l\u00e9gale<\/li>\n<li>La mise en \u0153uvre d\u2019un accord ou d\u2019un contrat<\/li>\n<li>La n\u00e9cessit\u00e9 issue d\u2019un int\u00e9r\u00eat l\u00e9gitime<\/li>\n<\/ul>\n\n\n\n<h2 class=\"small wp-block-heading\"><strong><strong>Pourquoi JOZ b.v. traite-t-il des donn\u00e9es\u00a0?<\/strong><\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Nous traitons par exemple des donn\u00e9es pour\u00a0:<\/p>\n\n\n\n<ul class=\"children_has_gear_icon\">\n<li>Une demande de devis, de newsletter, de formation ou d\u2019un autre service<\/li>\n<li>L\u2019envoi ou l\u2019acc\u00e8s donn\u00e9 \u00e0 du contenu ou \u00e0 de l\u2019information (gratuits)<\/li>\n<li>Les informations donn\u00e9es sur des \u00e9v\u00e9nements (occasionnels) ou des activit\u00e9s (marketing)<\/li>\n<li>Des e-mails (automatis\u00e9s) ax\u00e9s sur le service<\/li>\n<\/ul>\n\n\n\n<h2 class=\"small wp-block-heading\"><strong><strong>Quelles donn\u00e9es traitons-nous\u00a0?<\/strong><\/strong><\/h2>\n\n\n\n<ul class=\"children_has_gear_icon\">\n<li>Le nom de l\u2019entreprise<\/li>\n<li>Le nom du contact<\/li>\n<li>Le si\u00e8ge social et\/ou l\u2019adresse de facturation de l\u2019entreprise<\/li>\n<li>Un num\u00e9ro de t\u00e9l\u00e9phone (d\u2019un contact ou de contacts au sein) de l\u2019entreprise<\/li>\n<li>Une adresse e-mail (d\u2019un contact ou de contacts au sein) de l\u2019entreprise<\/li>\n<\/ul>\n\n\n\n<h2 class=\"small wp-block-heading\"><strong><strong>Comment traitons-nous ces donn\u00e9es\u00a0?<\/strong><\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les donn\u00e9es sp\u00e9cifiques que nous traitons d\u00e9pendent du consentement que vous nous avez donn\u00e9 ou de la finalit\u00e9 du traitement. Pour pouvoir vous envoyer le calcul du retour sur investissement, nous vous demandons un certain nombre de donn\u00e9es. \u00c0 savoir\u00a0:<\/p>\n\n\n\n<ul class=\"children_has_gear_icon\">\n<li>Le nombre de vaches<\/li>\n<li>La production de lait par vache<\/li>\n<li>Le prix du lait<\/li>\n<li>Le nombre de minutes par jour pass\u00e9es \u00e0 pousser du fourrage<\/li>\n<li>Votre adresse e-mail<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Nous traitons toutes les donn\u00e9es dans un environnement s\u00e9curis\u00e9. Ces donn\u00e9es ne sont accessibles qu\u2019aux employ\u00e9s qui en ont besoin pour effectuer leurs t\u00e2ches. Cela se fait bien entendu dans l\u2019int\u00e9r\u00eat de la personne concern\u00e9e et\/ou de la prestation de services. Ces employ\u00e9s ne voient que les donn\u00e9es n\u00e9cessaires \u00e0 un objectif donn\u00e9.<\/p>\n\n\n\n<h2 class=\"small wp-block-heading\"><strong><strong>D\u00e9sinscription des services<\/strong><\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Vous pouvez toujours vous d\u00e9sinscrire des services de JOZ b.v. Dans le cadre d\u2019un accord, nous vous demandons de respecter le d\u00e9lai de r\u00e9siliation convenu. Chaque newsletter propose la possibilit\u00e9 de se d\u00e9sabonner de nos newsletters.<\/p>\n\n\n\n<h2 class=\"small wp-block-heading\"><strong><strong>Consultation ou modification des donn\u00e9es<\/strong><\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Vous pouvez \u00e0 tout moment demander de consulter, modifier, rectifier ou d\u00e9truire vos donn\u00e9es. Pour cela, envoyez un e-mail \u00e0 <a href=\"mailto:info@joz.nl\">info@joz.nl<\/a>. JOZ b.v. r\u00e9pondra \u00e0 votre demande dans un d\u00e9lai de 4 semaines. Si vous avez des questions sp\u00e9cifiques concernant vos donn\u00e9es, n\u2019h\u00e9sitez pas \u00e0 envoyer un message \u00e0 la m\u00eame adresse e-mail. Nous y r\u00e9pondrons \u00e9galement dans un d\u00e9lai de 4 semaines.<\/p>\n\n\n\n<h2 class=\"small wp-block-heading\"><strong><strong>Comportement de clic et adresse IP<\/strong><\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Pour optimiser les sites et\/ou les services de JOZ b.v., nous conservons des donn\u00e9es g\u00e9n\u00e9rales sur les visiteurs. Ces donn\u00e9es ne peuvent pas \u00eatre rattach\u00e9es \u00e0 une entreprise ou \u00e0 une personne. Pour ce faire, JOZ b.v. utilise \u00e9galement l\u2019adresse IP de votre ordinateur. Cette adresse IP est un num\u00e9ro attribu\u00e9 automatiquement \u00e0 votre ordinateur lorsque vous \u00eates connect\u00e9 \u00e0 internet.<\/p>\n\n\n\n<h2 class=\"small wp-block-heading\"><strong><strong>Informations sur l\u2019utilisation des cookies<\/strong><\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Des cookies sont utilis\u00e9s sur le site web de JOZ, www.joz.nl. Les cookies sont des petits fichiers (texte) envoy\u00e9s avec les pages de notre site web. Ils sont stock\u00e9s par votre navigateur sur le disque dur de votre ordinateur, de votre tablette ou de votre t\u00e9l\u00e9phone. Cela garantit que votre navigateur internet peut \u00eatre reconnu par notre serveur web. Nous utilisons des cookies pour nous assurer que notre site web fonctionne de mani\u00e8re optimale et pour mieux comprendre les statistiques. Vous pouvez refuser d\u2019accepter les cookies. Vous ne pourrez alors peut-\u00eatre pas utiliser les possibilit\u00e9s sur notre (ou d\u2019autres) site web, ou seulement partiellement. Ci-dessous, nous donnons davantage de d\u00e9tails sur les cookies que nous utilisons.<\/p>\n\n\n\n<h2 class=\"small wp-block-heading\"><strong><strong>Cookies fonctionnels<\/strong><\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Notre site web utilise des cookies fonctionnels pour lui permettre de fonctionner. Ces cookies sont n\u00e9cessaires au bon fonctionnement du site web et \u00e0 l\u2019affichage correct des informations qu\u2019il contient.<\/p>\n\n\n\n<h2 class=\"small wp-block-heading\"><strong><strong>Cookies analytiques<\/strong><\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Notre site utilise \u00e9galement des cookies analytiques. Par exemple, nous utilisons Google Analytics pour savoir combien de visiteurs utilisent le site web et comment ils l\u2019utilisent. Ces informations anonymes permettent d\u2019am\u00e9liorer le site (\u00e0 l\u2019avenir). Google peut fournir ces informations \u00e0 des tiers si Google est l\u00e9galement tenu de le faire ou si des tiers traitent les informations pour le compte de Google.<\/p>\n\n\n\n<h2 class=\"small wp-block-heading\"><strong><strong>Cookies de marketing et cookies de suivi<\/strong><\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les cookies de marketing nous permettent par exemple d\u2019afficher des extraits de YouTube et de LinkedIn sur notre site web. Ces cookies peuvent \u00e9galement \u00eatre utilis\u00e9s pour afficher du contenu\/des publicit\u00e9s personnalis\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les cookies de suivi \u2013 qui sont plac\u00e9s \u00e0 des fins d\u2019analyse ou de publicit\u00e9 \u2013 sont des cookies tiers. Ces cookies ne sont pas plac\u00e9s par JOZ, mais par des tiers. Ces cookies servent, par exemple, \u00e0 adapter le contenu et les publicit\u00e9s \u00e0 votre comportement de navigation, afin que ceux-ci soient aussi pertinents que possible.<\/p>\n\n\n\n<h2 class=\"small wp-block-heading\"><strong><strong>Activer et d\u00e9sactiver les cookies et les supprimer<\/strong><\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Pour plus d\u2019informations sur l\u2019activation, la d\u00e9sactivation et la suppression des cookies, consultez les instructions et\/ou utilisez la fonction d\u2019aide de votre navigateur.<\/p>\n\n\n\n<h2 class=\"small wp-block-heading\"><strong><strong>Modifications<\/strong><\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">JOZ bv se r\u00e9serve le droit de modifier cette d\u00e9claration de confidentialit\u00e9. Vous recevrez une notification en cas de modifications importantes.<\/p>\n<\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"_acf_changed":false,"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-1823","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u00e9claration de confidentialit\u00e9 | JOZ<\/title>\n<meta name=\"description\" content=\"Chez JOZ, nous estimons qu\u2019il est tr\u00e8s important de prot\u00e9ger la confidentialit\u00e9 de nos clients et des visiteurs du site web.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/joz.nl\/fr\/declaration-de-confidentialite\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9claration de confidentialit\u00e9 | JOZ\" \/>\n<meta property=\"og:description\" content=\"Chez JOZ, nous estimons qu\u2019il est tr\u00e8s important de prot\u00e9ger la confidentialit\u00e9 de nos clients et des visiteurs du site web.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/joz.nl\/fr\/declaration-de-confidentialite\/\" \/>\n<meta property=\"og:site_name\" content=\"JOZ\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-15T09:46:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/joz.nl\\\/fr\\\/declaration-de-confidentialite\\\/\",\"url\":\"https:\\\/\\\/joz.nl\\\/fr\\\/declaration-de-confidentialite\\\/\",\"name\":\"D\u00e9claration de confidentialit\u00e9 | JOZ\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/joz.nl\\\/fr\\\/#website\"},\"datePublished\":\"2019-08-30T13:01:14+00:00\",\"dateModified\":\"2020-06-15T09:46:40+00:00\",\"description\":\"Chez JOZ, nous estimons qu\u2019il est tr\u00e8s important de prot\u00e9ger la confidentialit\u00e9 de nos clients et des visiteurs du site web.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/joz.nl\\\/fr\\\/declaration-de-confidentialite\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/joz.nl\\\/fr\\\/declaration-de-confidentialite\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/joz.nl\\\/fr\\\/declaration-de-confidentialite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/joz.nl\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00e9claration de confidentialit\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/joz.nl\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/joz.nl\\\/fr\\\/\",\"name\":\"JOZ\",\"description\":\"Home of the clean stable\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/joz.nl\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00e9claration de confidentialit\u00e9 | JOZ","description":"Chez JOZ, nous estimons qu\u2019il est tr\u00e8s important de prot\u00e9ger la confidentialit\u00e9 de nos clients et des visiteurs du site web.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/joz.nl\/fr\/declaration-de-confidentialite\/","og_locale":"fr_FR","og_type":"article","og_title":"D\u00e9claration de confidentialit\u00e9 | JOZ","og_description":"Chez JOZ, nous estimons qu\u2019il est tr\u00e8s important de prot\u00e9ger la confidentialit\u00e9 de nos clients et des visiteurs du site web.","og_url":"https:\/\/joz.nl\/fr\/declaration-de-confidentialite\/","og_site_name":"JOZ","article_modified_time":"2020-06-15T09:46:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/joz.nl\/fr\/declaration-de-confidentialite\/","url":"https:\/\/joz.nl\/fr\/declaration-de-confidentialite\/","name":"D\u00e9claration de confidentialit\u00e9 | JOZ","isPartOf":{"@id":"https:\/\/joz.nl\/fr\/#website"},"datePublished":"2019-08-30T13:01:14+00:00","dateModified":"2020-06-15T09:46:40+00:00","description":"Chez JOZ, nous estimons qu\u2019il est tr\u00e8s important de prot\u00e9ger la confidentialit\u00e9 de nos clients et des visiteurs du site web.","breadcrumb":{"@id":"https:\/\/joz.nl\/fr\/declaration-de-confidentialite\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/joz.nl\/fr\/declaration-de-confidentialite\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/joz.nl\/fr\/declaration-de-confidentialite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/joz.nl\/fr\/"},{"@type":"ListItem","position":2,"name":"D\u00e9claration de confidentialit\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/joz.nl\/fr\/#website","url":"https:\/\/joz.nl\/fr\/","name":"JOZ","description":"Home of the clean stable","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/joz.nl\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/joz.nl\/fr\/wp-json\/wp\/v2\/pages\/1823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/joz.nl\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/joz.nl\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/joz.nl\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/joz.nl\/fr\/wp-json\/wp\/v2\/comments?post=1823"}],"version-history":[{"count":6,"href":"https:\/\/joz.nl\/fr\/wp-json\/wp\/v2\/pages\/1823\/revisions"}],"predecessor-version":[{"id":5465,"href":"https:\/\/joz.nl\/fr\/wp-json\/wp\/v2\/pages\/1823\/revisions\/5465"}],"wp:attachment":[{"href":"https:\/\/joz.nl\/fr\/wp-json\/wp\/v2\/media?parent=1823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}