{"id":17539,"date":"2023-07-26T11:25:02","date_gmt":"2023-07-26T09:25:02","guid":{"rendered":"https:\/\/joz.nl\/?p=17539"},"modified":"2023-07-26T12:22:02","modified_gmt":"2023-07-26T10:22:02","slug":"le-stress-thermique-et-son-impact-sur-la-fertilite","status":"publish","type":"post","link":"https:\/\/joz.nl\/fr\/le-stress-thermique-et-son-impact-sur-la-fertilite\/","title":{"rendered":"Le stress thermique et son impact sur la fertilit\u00e9"},"content":{"rendered":"\n<div class=\"wp-block-g2p-wrapper\"><div class=\"container\"><div class=\"row\"><div class=\"col-12\">\n<p class=\"wp-block-paragraph\">Pendant les mois d\u2019\u00e9t\u00e9, le thermom\u00e8tre affiche des temp\u00e9ratures plus \u00e9lev\u00e9es. C\u2019est agr\u00e9able pour les humaines de se mettre dans l\u2019ambiance des vacances, mais les vaches supportent tr\u00e8s mal cette chaleur. \u00c0 des temp\u00e9ratures aussi basses que 20&nbsp;\u00b0C, elles peuvent d\u00e9j\u00e0 souffrir de ce que l\u2019on appelle le stress thermique. Cela peut avoir un impact n\u00e9gatif sur la fertilit\u00e9. Pourquoi la chaleur affecte-t-elle la fertilit\u00e9&nbsp;? Quelles mesures pouvez-vous prendre pour \u00e9viter que la temp\u00e9rature de votre \u00e9table ne devienne trop \u00e9lev\u00e9e&nbsp;?<\/p>\n\n\n\n<h2 class=\"wp-block-heading small\"><strong><strong>Stress thermique et fertilit\u00e9<\/strong><\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Dans un article pr\u00e9c\u00e9dent, nous avons parl\u00e9 de l\u2019<a href=\"https:\/\/joz.nl\/fr\/a-quel-moment-faut-il-opter-pour-un-robot-a-lisier-dans-son-etable-2\/\">am\u00e9lioration de la sant\u00e9 et de la fertilit\u00e9 des vaches gr\u00e2ce \u00e0 une meilleure hygi\u00e8ne de votre \u00e9table<\/a>. En mettant en place des mesures d\u2019hygi\u00e8ne \u00e0 temps, vous limitez les probl\u00e8mes tels que la mammite, les maladies des sabots et la baisse de fertilit\u00e9. Mais outre l\u2019hygi\u00e8ne de votre \u00e9table, un autre facteur peut affecter la fertilit\u00e9 des vaches&nbsp;: le stress thermique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le stress thermique survient lorsque la vache ne peut pas se refroidir. Le fonctionnement est le suivant. Chaque vache dispose d\u2019une zone thermoneutre. Dans cette zone, la vache n\u2019a pas besoin de d\u00e9penser de l\u2019\u00e9nergie suppl\u00e9mentaire pour maintenir sa temp\u00e9rature corporelle au m\u00eame niveau. \u00c0 partir de 20&nbsp;\u00b0C, les vaches ont besoin d\u2019une \u00e9nergie suppl\u00e9mentaire pour se refroidir et le stress appara\u00eet. Vous le remarquez lorsqu\u2019elles commencent \u00e0 haleter, \u00e0 transpirer, \u00e0 m\u00e2cher moins et \u00e0 vouloir boire beaucoup, par exemple.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les vaches souffrent-elles de stress thermique&nbsp;? Elles n\u2019ont alors qu\u2019une envie&nbsp;: se rafra\u00eechir. Cela peut affecter la fertilit\u00e9 et la sant\u00e9 des vaches.<\/p>\n\n\n\n<h2 class=\"wp-block-heading small\"><strong><strong>Quelles sont les cons\u00e9quences du stress thermique&nbsp;?<\/strong><\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Si la vache ne se refroidit pas, elle absorbe moins de fourrage, est moins active et produit moins de chaleur dans sa panse. Par cons\u00e9quent, la vache pr\u00e9sente un d\u00e9ficit \u00e9nerg\u00e9tique. En particulier chez les vaches en phase de d\u00e9marrage, cela peut entra\u00eener un bilan \u00e9nerg\u00e9tique tr\u00e8s n\u00e9gatif. Cela affecte la fertilit\u00e9&nbsp;: normalement, le taux de f\u00e9condation est d\u2019environ 90&nbsp;%, mais le stress thermique peut le r\u00e9duire \u00e0 55&nbsp;%.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lorsque les vaches souffrent de stress thermique, elles ont moins d\u2019app\u00e9tit pour la nourriture. En dig\u00e9rant, elles produisent de la chaleur et elles n\u2019aiment pas \u00e7a. N\u00e9anmoins, il est important que les vaches continuent \u00e0 manger suffisamment. Dans le cas contraire, une acidification de la panse peut m\u00eame se produire. Les vaches restent plus longtemps pour se rafra\u00eechir et ruminent moins, car elles respirent plus vite \u00e0 cause de la chaleur. L\u2019\u00e9quilibre entre la charge acide et la capacit\u00e9 tampon de la panse est perturb\u00e9. La r\u00e9sistance de la vache s\u2019en trouve diminu\u00e9e, ce qui la rend plus vuln\u00e9rable aux maladies.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vous voulez \u00e9viter cela&nbsp;? Essayez alors de r\u00e9agir \u00e0 temps aux cons\u00e9quences possibles du stress thermique. N\u2019attendez pas les signaux, adoptez une approche proactive.<\/p>\n\n\n\n<h2 class=\"wp-block-heading small\">L\u2019\u00e9table doit \u00eatre fra\u00eeche<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Une bonne ventilation peut contribuer \u00e0 la fra\u00eecheur de l\u2019\u00e9table. Cela maintient l\u2019humidit\u00e9 \u00e0 un faible niveau, ce qui permet \u00e0 la vache de mieux restituer sa chaleur. La circulation l\u00e9g\u00e8re permet \u00e0 la peau de se refroidir. Essayez de maintenir la temp\u00e9rature dans l\u2019\u00e9table \u00e0 peu pr\u00e8s au m\u00eame niveau que la temp\u00e9rature ext\u00e9rieure. Le meilleur moyen d\u2019y parvenir est d\u2019utiliser un ventilateur m\u00e9canique. Si n\u00e9cessaire, vous pouvez combiner la ventilation avec des brumisateurs ou des pulv\u00e9risateurs.<\/p>\n\n\n\n<h2 class=\"wp-block-heading small\">Maintenez l\u2019\u00e9table propre et s\u00e8che<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019\u00e9table doit non seulement \u00eatre fra\u00eeche, elle doit aussi \u00eatre propre. Par temps chaud, cela m\u00e9rite encore plus d\u2019attention. En effet, la chaleur permet aux bact\u00e9ries de se d\u00e9velopper et cela peut rendre les vaches malades. Si les vaches subissent un stress thermique, elles sont \u00e9galement plus sensibles aux maladies. Pour y rem\u00e9dier, il est important de nettoyer r\u00e9guli\u00e8rement le sol d\u2019\u00e9table.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une <a href=\"http:\/\/L\u2019\u00e9table doit non seulement \u00eatre fra\u00eeche, elle doit aussi \u00eatre propre. Par temps chaud, cela m\u00e9rite encore plus d\u2019attention. En effet, la chaleur permet aux bact\u00e9ries de se d\u00e9velopper et cela peut rendre les vaches malades. Si les vaches subissent un stress thermique, elles sont \u00e9galement plus sensibles aux maladies. Pour y rem\u00e9dier, il est important de nettoyer r\u00e9guli\u00e8rement le sol d\u2019\u00e9table.   Une meilleure hygi\u00e8ne garantit l\u2019am\u00e9lioration de la sant\u00e9 de vos vaches. Ceci, \u00e0 son tour, contribue \u00e0 la fertilit\u00e9 ! Faites donc travailler votre racleur \u00e0 lisier ou votre robot \u00e0 lisier r\u00e9guli\u00e8rement !\">meilleure hygi\u00e8ne<\/a> garantit l\u2019am\u00e9lioration de la sant\u00e9 de vos vaches. Ceci, \u00e0 son tour, contribue \u00e0 la fertilit\u00e9&nbsp;! Faites donc travailler votre&nbsp;<a href=\"https:\/\/joz.nl\/fr\/categorie\/racleurs-a-lisier\/\">racleur \u00e0 lisier<\/a>&nbsp;ou votre <a href=\"https:\/\/joz.nl\/fr\/categorie\/robots-a-lisier\/\">robot \u00e0 lisier<\/a> r\u00e9guli\u00e8rement&nbsp;!<\/p>\n\n\n\n<h2 class=\"wp-block-heading small\"><strong>Donnez le fourrage aux heures fra\u00eeches<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Avec le temps chaud, il est important que les vaches continuent \u00e0 manger suffisamment. Il faut donc les nourrir plusieurs fois par jour aux heures fra\u00eeches. En <a href=\"https:\/\/joz.nl\/fr\/categorie\/alimentation-plus-intelligente\/\">alimentant de mani\u00e8re plus intelligente<\/a> avec le robot repousse-fourrage Moov 2.0, vous vous assurez que vos vaches disposent de fourrage frais 24\/7 et vous garantissez un meilleur \u00e9quilibre \u00e9nerg\u00e9tique. Cela r\u00e9duit le risque d\u2019acidification de la panse.<\/p>\n\n\n\n<h2 class=\"wp-block-heading small\"><strong>Donnez suffisamment d\u2019eau<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Comme les humains, les vaches doivent boire beaucoup d\u2019eau propre par temps chaud. Par temps chaud, les besoins peuvent augmenter de 50&nbsp;%. Conseil&nbsp;: l\u2019eau ne doit pas n\u00e9cessairement \u00eatre froide.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading small\"><strong>Vous souhaitez en savoir plus&nbsp;?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Vous voulez en savoir plus sur la fertilit\u00e9 optimale et la sant\u00e9 des vaches&nbsp;? Et sur la mani\u00e8re dont les solutions de JOZ peuvent y contribuer&nbsp;? Prenez contact avec un&nbsp;<a href=\"https:\/\/joz.nl\/fr\/revendeurs\/\">revendeur pr\u00e8s de chez vous<\/a>&nbsp;ou demandez directement un&nbsp;<a href=\"https:\/\/joz.nl\/fr\/demander-un-devis\/\">devis<\/a>&nbsp;sur notre site web.<\/p>\n<\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le stress thermique a un impact n\u00e9gatif sur la fertilit\u00e9 des vaches. D\u00e9couvrez comment l\u2019\u00e9viter. <\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[71],"tags":[],"class_list":["post-17539","post","type-post","status-publish","format-standard","hentry","category-kennis-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le stress thermique et son impact sur la fertilit\u00e9<\/title>\n<meta name=\"description\" content=\"Le stress thermique a un impact n\u00e9gatif sur la fertilit\u00e9 des vaches. D\u00e9couvrez comment l\u2019\u00e9viter.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/joz.nl\/fr\/le-stress-thermique-et-son-impact-sur-la-fertilite\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le stress thermique et son impact sur la fertilit\u00e9\" \/>\n<meta property=\"og:description\" content=\"Le stress thermique a un impact n\u00e9gatif sur la fertilit\u00e9 des vaches. D\u00e9couvrez comment l\u2019\u00e9viter.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/joz.nl\/fr\/le-stress-thermique-et-son-impact-sur-la-fertilite\/\" \/>\n<meta property=\"og:site_name\" content=\"JOZ\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-26T09:25:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-26T10:22:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/joz.nl\/app\/uploads\/2023\/07\/Hittestress-JOZ-BLOG.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cmadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Le stress thermique et son impact sur la fertilit\u00e9\" \/>\n<meta name=\"twitter:description\" content=\"Le stress thermique a un impact n\u00e9gatif sur la fertilit\u00e9 des vaches. D\u00e9couvrez comment l\u2019\u00e9viter.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/joz.nl\/app\/uploads\/2023\/07\/Hittestress-JOZ-BLOG.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cmadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/joz.nl\\\/fr\\\/le-stress-thermique-et-son-impact-sur-la-fertilite\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/joz.nl\\\/fr\\\/le-stress-thermique-et-son-impact-sur-la-fertilite\\\/\"},\"author\":{\"name\":\"cmadmin\",\"@id\":\"https:\\\/\\\/joz.nl\\\/fr\\\/#\\\/schema\\\/person\\\/e2969093db2da1dbb3533b8771934ad4\"},\"headline\":\"Le stress thermique et son impact sur la fertilit\u00e9\",\"datePublished\":\"2023-07-26T09:25:02+00:00\",\"dateModified\":\"2023-07-26T10:22:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/joz.nl\\\/fr\\\/le-stress-thermique-et-son-impact-sur-la-fertilite\\\/\"},\"wordCount\":918,\"commentCount\":0,\"articleSection\":[\"Connaissance\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/joz.nl\\\/fr\\\/le-stress-thermique-et-son-impact-sur-la-fertilite\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/joz.nl\\\/fr\\\/le-stress-thermique-et-son-impact-sur-la-fertilite\\\/\",\"url\":\"https:\\\/\\\/joz.nl\\\/fr\\\/le-stress-thermique-et-son-impact-sur-la-fertilite\\\/\",\"name\":\"Le stress thermique et son impact sur la fertilit\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/joz.nl\\\/fr\\\/#website\"},\"datePublished\":\"2023-07-26T09:25:02+00:00\",\"dateModified\":\"2023-07-26T10:22:02+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/joz.nl\\\/fr\\\/#\\\/schema\\\/person\\\/e2969093db2da1dbb3533b8771934ad4\"},\"description\":\"Le stress thermique a un impact n\u00e9gatif sur la fertilit\u00e9 des vaches. D\u00e9couvrez comment l\u2019\u00e9viter.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/joz.nl\\\/fr\\\/le-stress-thermique-et-son-impact-sur-la-fertilite\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/joz.nl\\\/fr\\\/le-stress-thermique-et-son-impact-sur-la-fertilite\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/joz.nl\\\/fr\\\/le-stress-thermique-et-son-impact-sur-la-fertilite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/joz.nl\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Connaissance\",\"item\":\"https:\\\/\\\/joz.nl\\\/fr\\\/category\\\/kennis-fr\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Le stress thermique et son impact sur la fertilit\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/joz.nl\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/joz.nl\\\/fr\\\/\",\"name\":\"JOZ\",\"description\":\"Home of the clean stable\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/joz.nl\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/joz.nl\\\/fr\\\/#\\\/schema\\\/person\\\/e2969093db2da1dbb3533b8771934ad4\",\"name\":\"cmadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8bd6b56b1a1115550ba66c0d270851294e494d0dd06f354f06e636fab0e786dd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8bd6b56b1a1115550ba66c0d270851294e494d0dd06f354f06e636fab0e786dd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8bd6b56b1a1115550ba66c0d270851294e494d0dd06f354f06e636fab0e786dd?s=96&d=mm&r=g\",\"caption\":\"cmadmin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le stress thermique et son impact sur la fertilit\u00e9","description":"Le stress thermique a un impact n\u00e9gatif sur la fertilit\u00e9 des vaches. D\u00e9couvrez comment l\u2019\u00e9viter.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/joz.nl\/fr\/le-stress-thermique-et-son-impact-sur-la-fertilite\/","og_locale":"fr_FR","og_type":"article","og_title":"Le stress thermique et son impact sur la fertilit\u00e9","og_description":"Le stress thermique a un impact n\u00e9gatif sur la fertilit\u00e9 des vaches. D\u00e9couvrez comment l\u2019\u00e9viter.","og_url":"https:\/\/joz.nl\/fr\/le-stress-thermique-et-son-impact-sur-la-fertilite\/","og_site_name":"JOZ","article_published_time":"2023-07-26T09:25:02+00:00","article_modified_time":"2023-07-26T10:22:02+00:00","og_image":[{"width":1170,"height":750,"url":"https:\/\/joz.nl\/app\/uploads\/2023\/07\/Hittestress-JOZ-BLOG.jpg","type":"image\/jpeg"}],"author":"cmadmin","twitter_card":"summary_large_image","twitter_title":"Le stress thermique et son impact sur la fertilit\u00e9","twitter_description":"Le stress thermique a un impact n\u00e9gatif sur la fertilit\u00e9 des vaches. D\u00e9couvrez comment l\u2019\u00e9viter.","twitter_image":"https:\/\/joz.nl\/app\/uploads\/2023\/07\/Hittestress-JOZ-BLOG.jpg","twitter_misc":{"\u00c9crit par":"cmadmin","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/joz.nl\/fr\/le-stress-thermique-et-son-impact-sur-la-fertilite\/#article","isPartOf":{"@id":"https:\/\/joz.nl\/fr\/le-stress-thermique-et-son-impact-sur-la-fertilite\/"},"author":{"name":"cmadmin","@id":"https:\/\/joz.nl\/fr\/#\/schema\/person\/e2969093db2da1dbb3533b8771934ad4"},"headline":"Le stress thermique et son impact sur la fertilit\u00e9","datePublished":"2023-07-26T09:25:02+00:00","dateModified":"2023-07-26T10:22:02+00:00","mainEntityOfPage":{"@id":"https:\/\/joz.nl\/fr\/le-stress-thermique-et-son-impact-sur-la-fertilite\/"},"wordCount":918,"commentCount":0,"articleSection":["Connaissance"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/joz.nl\/fr\/le-stress-thermique-et-son-impact-sur-la-fertilite\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/joz.nl\/fr\/le-stress-thermique-et-son-impact-sur-la-fertilite\/","url":"https:\/\/joz.nl\/fr\/le-stress-thermique-et-son-impact-sur-la-fertilite\/","name":"Le stress thermique et son impact sur la fertilit\u00e9","isPartOf":{"@id":"https:\/\/joz.nl\/fr\/#website"},"datePublished":"2023-07-26T09:25:02+00:00","dateModified":"2023-07-26T10:22:02+00:00","author":{"@id":"https:\/\/joz.nl\/fr\/#\/schema\/person\/e2969093db2da1dbb3533b8771934ad4"},"description":"Le stress thermique a un impact n\u00e9gatif sur la fertilit\u00e9 des vaches. D\u00e9couvrez comment l\u2019\u00e9viter.","breadcrumb":{"@id":"https:\/\/joz.nl\/fr\/le-stress-thermique-et-son-impact-sur-la-fertilite\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/joz.nl\/fr\/le-stress-thermique-et-son-impact-sur-la-fertilite\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/joz.nl\/fr\/le-stress-thermique-et-son-impact-sur-la-fertilite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/joz.nl\/fr\/"},{"@type":"ListItem","position":2,"name":"Connaissance","item":"https:\/\/joz.nl\/fr\/category\/kennis-fr\/"},{"@type":"ListItem","position":3,"name":"Le stress thermique et son impact sur la fertilit\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/joz.nl\/fr\/#website","url":"https:\/\/joz.nl\/fr\/","name":"JOZ","description":"Home of the clean stable","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/joz.nl\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/joz.nl\/fr\/#\/schema\/person\/e2969093db2da1dbb3533b8771934ad4","name":"cmadmin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/8bd6b56b1a1115550ba66c0d270851294e494d0dd06f354f06e636fab0e786dd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8bd6b56b1a1115550ba66c0d270851294e494d0dd06f354f06e636fab0e786dd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8bd6b56b1a1115550ba66c0d270851294e494d0dd06f354f06e636fab0e786dd?s=96&d=mm&r=g","caption":"cmadmin"}}]}},"_links":{"self":[{"href":"https:\/\/joz.nl\/fr\/wp-json\/wp\/v2\/posts\/17539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/joz.nl\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/joz.nl\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/joz.nl\/fr\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/joz.nl\/fr\/wp-json\/wp\/v2\/comments?post=17539"}],"version-history":[{"count":4,"href":"https:\/\/joz.nl\/fr\/wp-json\/wp\/v2\/posts\/17539\/revisions"}],"predecessor-version":[{"id":17570,"href":"https:\/\/joz.nl\/fr\/wp-json\/wp\/v2\/posts\/17539\/revisions\/17570"}],"wp:attachment":[{"href":"https:\/\/joz.nl\/fr\/wp-json\/wp\/v2\/media?parent=17539"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/joz.nl\/fr\/wp-json\/wp\/v2\/categories?post=17539"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/joz.nl\/fr\/wp-json\/wp\/v2\/tags?post=17539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}